{"id":163,"date":"2018-04-07T19:48:57","date_gmt":"2018-04-08T02:48:57","guid":{"rendered":"https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS.jpg"},"modified":"2025-10-28T12:57:03","modified_gmt":"2025-10-28T19:57:03","slug":"bonsallhs","status":"inherit","type":"attachment","link":"https:\/\/www.palomar.edu\/dualenrollment\/school-districts\/bonsallhs\/","title":{"rendered":"Bonsall High School"},"author":229,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"isc_image_source":"","isc_image_source_url":"","isc_image_licence":"","isc_image_source_own":false},"class_list":["post-163","attachment","type-attachment","status-inherit","hentry"],"acf":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/agumIC-2D","description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"&quot;&quot;\" srcset=\"https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS-300x300.jpg 300w, https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS-150x150.jpg 150w, https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"\"\"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":400,"height":400,"file":"2018\/04\/BonsallHS.jpg","sizes":{"thumbnail":{"file":"BonsallHS-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS-150x150.jpg"},"medium":{"file":"BonsallHS-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS-300x300.jpg"},"sow-carousel-default":{"file":"BonsallHS-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS-272x182.jpg"},"full":{"file":"BonsallHS.jpg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":115,"source_url":"https:\/\/www.palomar.edu\/dualenrollment\/wp-content\/uploads\/sites\/195\/2018\/04\/BonsallHS.jpg","_links":{"self":[{"href":"https:\/\/www.palomar.edu\/dualenrollment\/wp-json\/wp\/v2\/media\/163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palomar.edu\/dualenrollment\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.palomar.edu\/dualenrollment\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.palomar.edu\/dualenrollment\/wp-json\/wp\/v2\/users\/229"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palomar.edu\/dualenrollment\/wp-json\/wp\/v2\/comments?post=163"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":115,"href":"https:\/\/www.palomar.edu\/dualenrollment\/wp-json\/wp\/v2\/pages\/115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}