{"id":82,"date":"2015-04-24T22:03:49","date_gmt":"2015-04-24T22:03:49","guid":{"rendered":"http:\/\/www.palomar.edu\/pages\/azindex\/?p=82"},"modified":"2022-03-22T00:10:47","modified_gmt":"2022-03-22T00:10:47","slug":"business-administration","status":"publish","type":"post","link":"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/","title":{"rendered":"Business Administration"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-82","post","type-post","status-publish","format-standard","hentry","category-site-index"],"acf":{"url":"www.palomar.edu\/business\/","force_ssl":true,"custom_sort_text":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Business Administration - A-Z Index<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Business Administration - A-Z Index\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/\" \/>\n<meta property=\"og:site_name\" content=\"A-Z Index\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-24T22:03:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-22T00:10:47+00:00\" \/>\n<meta name=\"author\" content=\"Norcross, Chris\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Norcross, Chris\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/2015\\\/04\\\/24\\\/business-administration\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/2015\\\/04\\\/24\\\/business-administration\\\/\"},\"author\":{\"name\":\"Norcross, Chris\",\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/#\\\/schema\\\/person\\\/021f7603102e8730cff2696f8924d065\"},\"headline\":\"Business Administration\",\"datePublished\":\"2015-04-24T22:03:49+00:00\",\"dateModified\":\"2022-03-22T00:10:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/2015\\\/04\\\/24\\\/business-administration\\\/\"},\"wordCount\":2,\"commentCount\":0,\"articleSection\":[\"Site Index\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/2015\\\/04\\\/24\\\/business-administration\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/2015\\\/04\\\/24\\\/business-administration\\\/\",\"url\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/2015\\\/04\\\/24\\\/business-administration\\\/\",\"name\":\"Business Administration - A-Z Index\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/#website\"},\"datePublished\":\"2015-04-24T22:03:49+00:00\",\"dateModified\":\"2022-03-22T00:10:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/#\\\/schema\\\/person\\\/021f7603102e8730cff2696f8924d065\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/2015\\\/04\\\/24\\\/business-administration\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/2015\\\/04\\\/24\\\/business-administration\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/2015\\\/04\\\/24\\\/business-administration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business Administration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/#website\",\"url\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/\",\"name\":\"A-Z Index\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.palomar.edu\\\/azindex\\\/#\\\/schema\\\/person\\\/021f7603102e8730cff2696f8924d065\",\"name\":\"Norcross, Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/beb3a9e0aee0bcd1b818784d6757442c141a1e49ffaaf6b8b79b92d0d790dd05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/beb3a9e0aee0bcd1b818784d6757442c141a1e49ffaaf6b8b79b92d0d790dd05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/beb3a9e0aee0bcd1b818784d6757442c141a1e49ffaaf6b8b79b92d0d790dd05?s=96&d=mm&r=g\",\"caption\":\"Norcross, Chris\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Business Administration - A-Z Index","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/","og_locale":"en_US","og_type":"article","og_title":"Business Administration - A-Z Index","og_url":"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/","og_site_name":"A-Z Index","article_published_time":"2015-04-24T22:03:49+00:00","article_modified_time":"2022-03-22T00:10:47+00:00","author":"Norcross, Chris","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Norcross, Chris"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/#article","isPartOf":{"@id":"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/"},"author":{"name":"Norcross, Chris","@id":"https:\/\/www.palomar.edu\/azindex\/#\/schema\/person\/021f7603102e8730cff2696f8924d065"},"headline":"Business Administration","datePublished":"2015-04-24T22:03:49+00:00","dateModified":"2022-03-22T00:10:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/"},"wordCount":2,"commentCount":0,"articleSection":["Site Index"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/","url":"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/","name":"Business Administration - A-Z Index","isPartOf":{"@id":"https:\/\/www.palomar.edu\/azindex\/#website"},"datePublished":"2015-04-24T22:03:49+00:00","dateModified":"2022-03-22T00:10:47+00:00","author":{"@id":"https:\/\/www.palomar.edu\/azindex\/#\/schema\/person\/021f7603102e8730cff2696f8924d065"},"breadcrumb":{"@id":"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.palomar.edu\/azindex\/2015\/04\/24\/business-administration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.palomar.edu\/azindex\/"},{"@type":"ListItem","position":2,"name":"Business Administration"}]},{"@type":"WebSite","@id":"https:\/\/www.palomar.edu\/azindex\/#website","url":"https:\/\/www.palomar.edu\/azindex\/","name":"A-Z Index","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.palomar.edu\/azindex\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.palomar.edu\/azindex\/#\/schema\/person\/021f7603102e8730cff2696f8924d065","name":"Norcross, Chris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/beb3a9e0aee0bcd1b818784d6757442c141a1e49ffaaf6b8b79b92d0d790dd05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/beb3a9e0aee0bcd1b818784d6757442c141a1e49ffaaf6b8b79b92d0d790dd05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/beb3a9e0aee0bcd1b818784d6757442c141a1e49ffaaf6b8b79b92d0d790dd05?s=96&d=mm&r=g","caption":"Norcross, Chris"}}]}},"_links":{"self":[{"href":"https:\/\/www.palomar.edu\/azindex\/wp-json\/wp\/v2\/posts\/82","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.palomar.edu\/azindex\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.palomar.edu\/azindex\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.palomar.edu\/azindex\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.palomar.edu\/azindex\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":2,"href":"https:\/\/www.palomar.edu\/azindex\/wp-json\/wp\/v2\/posts\/82\/revisions"}],"predecessor-version":[{"id":1194,"href":"https:\/\/www.palomar.edu\/azindex\/wp-json\/wp\/v2\/posts\/82\/revisions\/1194"}],"wp:attachment":[{"href":"https:\/\/www.palomar.edu\/azindex\/wp-json\/wp\/v2\/media?parent=82"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.palomar.edu\/azindex\/wp-json\/wp\/v2\/categories?post=82"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.palomar.edu\/azindex\/wp-json\/wp\/v2\/tags?post=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}